{"id":7000,"date":"2017-03-31T09:39:46","date_gmt":"2017-03-31T09:39:46","guid":{"rendered":"http:\/\/maison.edge-themes.com\/?page_id=7000"},"modified":"2026-05-11T15:19:11","modified_gmt":"2026-05-11T15:19:11","slug":"studio-home","status":"publish","type":"page","link":"https:\/\/boxolimpo.com\/en_us\/","title":{"rendered":"Box Olimpo M\u00e1laga &#8211; CrossFit M\u00e1laga &#8211; Hyrox M\u00e1laga"},"content":{"rendered":"<div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1490966074744 vc_column-gap-25\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-elements-holder edgtf-one-column edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-429229\" data-1280-1600=\"0 10% 0 15%\" data-1024-1280=\"0 5% 0 0%\" data-768-1024=\"0 50% 0 5%\" data-600-768=\"0 20% 0 20%\" data-480-600=\"0 20% 0 20%\" data-480=\"0 10% 0 10%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-429229\" style=\"padding: 0 8% 0 5%\">\n\t\t\t\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img width=\"600\" height=\"600\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/09\/boxolimpo-chicas.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"boxolimpo-chicas\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/09\/boxolimpo-chicas.jpg 600w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/09\/boxolimpo-chicas-150x150.jpg 150w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/09\/boxolimpo-chicas-300x300.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/09\/boxolimpo-chicas-550x550.jpg 550w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 11px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Ven a probar con nosotros, \u00a1GRATIS!<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 8px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>La mejor manera de saber realmente qu\u00e9 hacemos es contactar con nosotros y solicitar una clase de prueba (gratuita). En ella, nuestros entrenadores te explicar\u00e1n como funcionamos y realizar\u00e1s una clase con el resto de compa\u00f1eros, pero adaptada a tu nivel f\u00edsico y tus necesidades,<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 42px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/contacto\/\" target=\"_blank\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-solid\"  >\n    <span class=\"edgtf-btn-text\">Quiero ir a probar<\/span>\n    <\/a><div class=\"vc_empty_space\"   style=\"height: 10px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-image-with-text-holder    edgtf-iwm-center-align\">\n    <div class=\"edgtf-iwt-image\">\n                                    <img width=\"174\" height=\"174\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/trabaja-todo-tu-cuerpo.png\" class=\"attachment-full size-full\" alt=\"trabaja-todo-tu-cuerpo\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/trabaja-todo-tu-cuerpo.png 174w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/trabaja-todo-tu-cuerpo-150x150.png 150w\" sizes=\"(max-width: 174px) 100vw, 174px\" \/>                        <\/div>\n    <div class=\"edgtf-iwt-text-holder\">\n                    <h4 class=\"edgtf-iwt-title\" >TRABAJA TODO TU CUERPO<\/h4>\n        \t\t            <p class=\"edgtf-iwt-text\" >Combinamos diferentes deportes como son halterofilia, powerlifting, gimnasia art\u00edstica, atletismo, entrenamiento funcional... Apasionados por el crosstraining. Por lo que los movimientos utilizados reclutan gran cantidad de m\u00fasculos a la vez, en lugar de trabajarlos de manera aislada, lo que hace que sea un entrenamiento completo.<\/p>\n        \t\t    <\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-image-with-text-holder    edgtf-iwm-center-align\">\n    <div class=\"edgtf-iwt-image\">\n                                    <img width=\"174\" height=\"174\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/alta-intensidad.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/alta-intensidad.png 174w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/alta-intensidad-150x150.png 150w\" sizes=\"(max-width: 174px) 100vw, 174px\" \/>                        <\/div>\n    <div class=\"edgtf-iwt-text-holder\">\n                    <h4 class=\"edgtf-iwt-title\" >ALTA INTENSIDAD<\/h4>\n        \t\t            <p class=\"edgtf-iwt-text\" >Nuestros entrenamientos te hacen mantener un ritmo card\u00edaco elevado durante el WOD debido a la alta intensidad. Esto har\u00e1 que quemes muchas m\u00e1s calorias en menor tiempo y que las mejoras sean r\u00e1pidas debido al est\u00edmulo al que sometemos a nuestro cuerpo.<\/p>\n        \t\t    <\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"edgtf-image-with-text-holder    edgtf-iwm-center-align\">\n    <div class=\"edgtf-iwt-image\">\n                                    <img width=\"176\" height=\"176\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/variacion-constante.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/variacion-constante.png 176w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2019\/01\/variacion-constante-150x150.png 150w\" sizes=\"(max-width: 176px) 100vw, 176px\" \/>                        <\/div>\n    <div class=\"edgtf-iwt-text-holder\">\n                    <h4 class=\"edgtf-iwt-title\" >VARIACI\u00d3N CONSTANTE<\/h4>\n        \t\t            <p class=\"edgtf-iwt-text\" >Cada d\u00eda el entrenamiento es diferente, siempre estructurado en una parte de trabajo de Fuerza ( cada d\u00eda un ejercicio diferente) y una segunda parte de Metcon (acondicionamiento), en la que trabajaremos con mayor intensidad ( por rondas, por tiempo, intervalos, etc).<\/p>\n        \t\t    <\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_gmaps_widget wpb_content_element\"><h2 class=\"wpb_heading wpb_map_heading\">Encu\u00e9ntranos f\u00e1cil<\/h2><div class=\"wpb_wrapper\"><div class=\"wpb_map_wraper\"><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3198.7961861715175!2d-4.478692784712836!3d36.70343527996861!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd72f754761d0a41%3A0x6a127ead0a49cae1!2sBox+Olimpo+M%C3%A1laga+Crossfit!5e0!3m2!1ses!2ses!4v1533657298326\" width=\"800\" height=\"600\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper\"  ><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 33px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h4>Publicaciones<\/h4>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 33px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-blog-list-holder edgtf-bl-standard edgtf-bl-five-columns edgtf-bl-normal-space edgtf-bl-pag-no-pagination\"  data-type=standard data-number-of-posts=5 data-number-of-columns=5 data-space-between-columns=normal data-order-by=date data-order=DESC data-featured-image=yes data-image-size=full data-title-tag=h4 data-excerpt-length=40 data-post-info-section=yes data-post-info-image=yes data-post-info-author=no data-post-info-date=yes data-post-info-category=no data-post-info-comments=no data-pagination-type=no-pagination data-max-num-pages=167 data-next-page=2>\n\t<div class=\"edgtf-bl-wrapper\">\n\t\t<ul class=\"edgtf-blog-list\">\n\t\t\t<li class=\"edgtf-bl-item clearfix\">\n\t<div class=\"edgtf-bli-inner\">\n\t\t            \n\t<div class=\"edgtf-post-image\">\n        \t\t    <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-11-05-2026-al-17-05-2026\" title=\"Entrenamientos 11-05-2026 al 17-05-2026\">\n                            <img width=\"1244\" height=\"754\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg 1244w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-300x182.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-1024x621.jpg 1024w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-768x465.jpg 768w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-18x12.jpg 18w\" sizes=\"(max-width: 1244px) 100vw, 1244px\" \/>                \t\t    <\/a>\n        \t<\/div>\n\t\t\n\t\t<div class=\"edgtf-bli-content\">\n\t\t\t<div itemprop=\"dateCreated\" class=\"edgtf-post-info-date entry-date published updated\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/2026\/05\">\n    \n        May 12, 2026        <\/a>\n    <meta itemprop=\"interactionCount\" content=\"UserComments: 0\"\/>\n<\/div>\t\t\t\n<h4 itemprop=\"name\" class=\"entry-title edgtf-post-title\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-11-05-2026-al-17-05-2026\" title=\"Entrenamientos 11-05-2026 al 17-05-2026\">\n            Entrenamientos 11-05-2026 al 17-05-2026            <\/a>\n    <\/h4>\n\t\t\t\t\t\t<div class=\"edgtf-bli-excerpt\">\n\t\t\t\t\t\t<div class=\"edgtf-post-excerpt-holder\">\n\t\t\t<p itemprop=\"description\" class=\"edgtf-post-excerpt\">\n\t\t\t\t\nLUNES\n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nFront Squats\n\n\n\nc) Wod\n\n\n\nBurpees + DB Lunges + Run\n\n\n\nMARTES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBench Press + Strict pull ups + Ring Dips\n\n\n\nc) Wod\n\n\n\nHSPU + Subida a cuerda + DB Box Step up + KB Swing\n\n\n\nMI\u00c9RCOLES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nDeadlift + Curl b\u00edceps\n\n\n\nc)\t\t\t<\/p>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"edgtf-post-read-more-button\">\n\t<a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-11-05-2026-al-17-05-2026\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-blog-list-button\"  >    <span class=\"edgtf-btn-text\">READ MORE<\/span>    <\/a>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li><li class=\"edgtf-bl-item clearfix\">\n\t<div class=\"edgtf-bli-inner\">\n\t\t            \n\t<div class=\"edgtf-post-image\">\n        \t\t    <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-04-05-2026-al-10-05-2026\" title=\"Entrenamientos 04\/05\/2026 al 10\/05\/2026\">\n                            <img width=\"1244\" height=\"754\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg 1244w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-300x182.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-1024x621.jpg 1024w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-768x465.jpg 768w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-18x12.jpg 18w\" sizes=\"(max-width: 1244px) 100vw, 1244px\" \/>                \t\t    <\/a>\n        \t<\/div>\n\t\t\n\t\t<div class=\"edgtf-bli-content\">\n\t\t\t<div itemprop=\"dateCreated\" class=\"edgtf-post-info-date entry-date published updated\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/2026\/05\">\n    \n        May 4, 2026        <\/a>\n    <meta itemprop=\"interactionCount\" content=\"UserComments: 0\"\/>\n<\/div>\t\t\t\n<h4 itemprop=\"name\" class=\"entry-title edgtf-post-title\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-04-05-2026-al-10-05-2026\" title=\"Entrenamientos 04\/05\/2026 al 10\/05\/2026\">\n            Entrenamientos 04\/05\/2026 al 10\/05\/2026            <\/a>\n    <\/h4>\n\t\t\t\t\t\t<div class=\"edgtf-bli-excerpt\">\n\t\t\t\t\t\t<div class=\"edgtf-post-excerpt-holder\">\n\t\t\t<p itemprop=\"description\" class=\"edgtf-post-excerpt\">\n\t\t\t\t\nLUNES\n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nSnatch\n\n\n\nc) Wod\n\n\n\nHang Power Snatch + Burpees + T2B\n\n\n\nMARTES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nT\u00e9cnica: T2B o Shoulder press + Farmer Carry + Ring Row Hold\n\n\n\nc) Wod\n\n\n\nRussian KB Swing + Wtd Sit ups + Push Jerk\n\n\n\nMI\u00c9RCOLES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBack Squat + Chin\t\t\t<\/p>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"edgtf-post-read-more-button\">\n\t<a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-04-05-2026-al-10-05-2026\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-blog-list-button\"  >    <span class=\"edgtf-btn-text\">READ MORE<\/span>    <\/a>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li><li class=\"edgtf-bl-item clearfix\">\n\t<div class=\"edgtf-bli-inner\">\n\t\t            \n\t<div class=\"edgtf-post-image\">\n        \t\t    <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-13-04-2026-al-19-04-2026\" title=\"Entrenamientos 13\/04\/2026 al 19\/04\/2026\">\n                            <img width=\"1244\" height=\"754\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg 1244w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-300x182.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-1024x621.jpg 1024w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-768x465.jpg 768w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-18x12.jpg 18w\" sizes=\"(max-width: 1244px) 100vw, 1244px\" \/>                \t\t    <\/a>\n        \t<\/div>\n\t\t\n\t\t<div class=\"edgtf-bli-content\">\n\t\t\t<div itemprop=\"dateCreated\" class=\"edgtf-post-info-date entry-date published updated\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/2026\/04\">\n    \n        April 11, 2026        <\/a>\n    <meta itemprop=\"interactionCount\" content=\"UserComments: 0\"\/>\n<\/div>\t\t\t\n<h4 itemprop=\"name\" class=\"entry-title edgtf-post-title\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-13-04-2026-al-19-04-2026\" title=\"Entrenamientos 13\/04\/2026 al 19\/04\/2026\">\n            Entrenamientos 13\/04\/2026 al 19\/04\/2026            <\/a>\n    <\/h4>\n\t\t\t\t\t\t<div class=\"edgtf-bli-excerpt\">\n\t\t\t\t\t\t<div class=\"edgtf-post-excerpt-holder\">\n\t\t\t<p itemprop=\"description\" class=\"edgtf-post-excerpt\">\n\t\t\t\t\nLUNES\n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBench Press + Strict pull ups + Ring Dips\n\n\n\nc) Wod\n\n\n\nWall Walks + Run + HSPU + Lunges\n\n\n\nMARTES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nDeadlift + Broad Jump + Push ups\n\n\n\nc) Wod\n\n\n\n\"DT\"\n\n\n\nMI\u00c9RCOLES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBack Squat\n\n\n\nc) Wod\n\n\n\nDB Thruster + Burpees over the DB\t\t\t<\/p>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"edgtf-post-read-more-button\">\n\t<a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-13-04-2026-al-19-04-2026\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-blog-list-button\"  >    <span class=\"edgtf-btn-text\">READ MORE<\/span>    <\/a>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li><li class=\"edgtf-bl-item clearfix\">\n\t<div class=\"edgtf-bli-inner\">\n\t\t            \n\t<div class=\"edgtf-post-image\">\n        \t\t    <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-06-04-2026-al-12-04-2026\" title=\"Entrenamientos 06\/04\/2026 al 12\/04\/2026\">\n                            <img width=\"1244\" height=\"754\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg 1244w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-300x182.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-1024x621.jpg 1024w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-768x465.jpg 768w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-18x12.jpg 18w\" sizes=\"(max-width: 1244px) 100vw, 1244px\" \/>                \t\t    <\/a>\n        \t<\/div>\n\t\t\n\t\t<div class=\"edgtf-bli-content\">\n\t\t\t<div itemprop=\"dateCreated\" class=\"edgtf-post-info-date entry-date published updated\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/2026\/04\">\n    \n        April 7, 2026        <\/a>\n    <meta itemprop=\"interactionCount\" content=\"UserComments: 0\"\/>\n<\/div>\t\t\t\n<h4 itemprop=\"name\" class=\"entry-title edgtf-post-title\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-06-04-2026-al-12-04-2026\" title=\"Entrenamientos 06\/04\/2026 al 12\/04\/2026\">\n            Entrenamientos 06\/04\/2026 al 12\/04\/2026            <\/a>\n    <\/h4>\n\t\t\t\t\t\t<div class=\"edgtf-bli-excerpt\">\n\t\t\t\t\t\t<div class=\"edgtf-post-excerpt-holder\">\n\t\t\t<p itemprop=\"description\" class=\"edgtf-post-excerpt\">\n\t\t\t\t\nLUNES\n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBack Squat + Box Step up + Wall sit\n\n\n\nc) Wod\n\n\n\nGoblet squat + DB Hang C&amp;J + T2B\n\n\n\nMARTES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nReverse lunges + pinch grip walk\n\n\n\nc) Wod\n\n\n\nAmrap 7' \/ 3' rest \/ Amrap 7'\n\n\n\nDeadlift + Bar MU + 100\t\t\t<\/p>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"edgtf-post-read-more-button\">\n\t<a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-06-04-2026-al-12-04-2026\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-blog-list-button\"  >    <span class=\"edgtf-btn-text\">READ MORE<\/span>    <\/a>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li><li class=\"edgtf-bl-item clearfix\">\n\t<div class=\"edgtf-bli-inner\">\n\t\t            \n\t<div class=\"edgtf-post-image\">\n        \t\t    <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-23-03-2026-al-29-03-2026\" title=\"Entrenamientos 23\/03\/2026 al 29\/03\/2026\">\n                            <img width=\"1244\" height=\"754\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo.jpg 1244w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-300x182.jpg 300w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-1024x621.jpg 1024w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-768x465.jpg 768w, https:\/\/boxolimpo.com\/wp-content\/uploads\/2025\/05\/logo-box-olimpo-18x12.jpg 18w\" sizes=\"(max-width: 1244px) 100vw, 1244px\" \/>                \t\t    <\/a>\n        \t<\/div>\n\t\t\n\t\t<div class=\"edgtf-bli-content\">\n\t\t\t<div itemprop=\"dateCreated\" class=\"edgtf-post-info-date entry-date published updated\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/2026\/03\">\n    \n        March 23, 2026        <\/a>\n    <meta itemprop=\"interactionCount\" content=\"UserComments: 0\"\/>\n<\/div>\t\t\t\n<h4 itemprop=\"name\" class=\"entry-title edgtf-post-title\">\n            <a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-23-03-2026-al-29-03-2026\" title=\"Entrenamientos 23\/03\/2026 al 29\/03\/2026\">\n            Entrenamientos 23\/03\/2026 al 29\/03\/2026            <\/a>\n    <\/h4>\n\t\t\t\t\t\t<div class=\"edgtf-bli-excerpt\">\n\t\t\t\t\t\t<div class=\"edgtf-post-excerpt-holder\">\n\t\t\t<p itemprop=\"description\" class=\"edgtf-post-excerpt\">\n\t\t\t\t\nLUNES\n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nBack Squat + Lunges + A-Jumps\n\n\n\nc) Wod\n\n\n\nThruster \/ V-ups \/ Pull ups\n\n\n\nMARTES \n\n\n\na) Calentamiento\n\n\n\nb) Fuerza\n\n\n\nKB Swing + Run\/Machine + T2B\n\n\n\nc) Wod\n\n\n\nAmrap 20' - Parejas\n\n\n\nMI\u00c9RCOLES \n\n\n\na) Calentamiento\n\n\n\nb) Wod\n\n\n\nEstaciones: Trineo \/ Sandbag Clean \/ WB Sit ups \/ Box Jump\t\t\t<\/p>\n\t\t<\/div>\n\t\t\t\t\t\t<div class=\"edgtf-post-read-more-button\">\n\t<a itemprop=\"url\" href=\"https:\/\/boxolimpo.com\/en_us\/entrenamientos-23-03-2026-al-29-03-2026\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-simple edgtf-blog-list-button\"  >    <span class=\"edgtf-btn-text\">READ MORE<\/span>    <\/a>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/li>\t\t<\/ul>\n\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"edgtf-row-grid-section-wrapper edgtf-content-aligment-center\"  style=\"background-color:#f5f5f5\"><div class=\"edgtf-row-grid-section\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1491311178693 vc_column-gap-25\" ><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1490961217212\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h6>Conecta con nosotros<\/h6>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 33px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-elements-holder edgtf-two-columns edgtf-responsive-mode-never\" ><div class=\"edgtf-eh-item\"  data-item-class=\"edgtf-eh-custom-511604\" data-768-1024=\"0 0 0 5%\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-511604\" style=\"padding: 0 0 0 35%\">\n\t\t\t<div class=\"edgtf-iwt clearfix edgtf-iwt-icon-top edgtf-iwt-icon-medium edgtf-iwt-center-align edgtf-iwt-vertical-middle\">\n\t<div class=\"edgtf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/www.facebook.com\/boxolimpomalaga\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t    <span class=\"edgtf-icon-shortcode edgtf-normal\"  data-hover-color=\"#767677\" data-color=\"#231f20\">\n                    <i class=\"edgtf-icon-font-awesome fa fa-facebook edgtf-icon-element\" style=\"color: #231f20;font-size:25px\" ><\/i>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"edgtf-iwt-content\" style=\"padding-top: 0px\">\n\t\t\t\t\t\t\t<p class=\"edgtf-iwt-text\" style=\"color: #333333;font-size: 11px;margin-top: 0px\">Facebook<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 30px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-iwt clearfix edgtf-iwt-icon-top edgtf-iwt-icon-medium edgtf-iwt-center-align edgtf-iwt-vertical-middle\">\n\t<div class=\"edgtf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/instragram.com\/boxolimpomalaga\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t    <span class=\"edgtf-icon-shortcode edgtf-normal\"  data-hover-color=\"#767677\" data-color=\"#231f20\">\n                    <i class=\"edgtf-icon-font-awesome fa fa-instagram edgtf-icon-element\" style=\"color: #231f20;font-size:25px\" ><\/i>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"edgtf-iwt-content\" style=\"padding-top: 0px\">\n\t\t\t\t\t\t\t<p class=\"edgtf-iwt-text\" style=\"color: #333333;font-size: 11px;margin-top: 0px\">Instagram<\/p>\n\t\t\t<\/div>\n<\/div><div class=\"vc_empty_space\"   style=\"height: 30px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1490961226490\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h6>Horario<\/h6>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 14px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><h3 style=\"text-align: center;font-family:Abril Fatface;font-weight:400;font-style:normal\" class=\"vc_custom_heading\" >De 7:00h a 22:00h<\/h3>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Abrimos ininterrumpidamente para que elijas el horario que mejor se adapte a tu d\u00eda a d\u00eda.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 7px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1490964950984\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h6>Entrenadores cualificados<\/h6>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 14px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Coaches Graduados en Ciencias de la Actividad F\u00edsica y el Deporte, TAFAD, Level I y Level II Crossfit, Endurance y Entrenadores de Halterofilia, Fuerza y Musculaci\u00f3n por la Federaci\u00f3n Espa\u00f1ola de Halterofilia.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 35px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"edgtf-elements-holder edgtf-one-column edgtf-responsive-mode-768\" ><div class=\"edgtf-eh-item edgtf-horizontal-alignment-center\"  data-item-class=\"edgtf-eh-custom-134944\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-134944\" style=\"padding: 0 5%\">\n\t\t\t<div class=\"edgtf-clients-wc-holder  edgtf-ch-columns-1 edgtf-ch-no-space edgtf-ch-alignment-center edgtf-cc-hover-switch-images\"><div class=\"edgtf-ch-inner\"><div class=\"edgtf-cc-item\">\n\t\t\t<a itemprop=\"url\" class=\"edgtf-cc-link edgtf-block-drag-link\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t<img itemprop=\"image\" class=\"edgtf-cc-image\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/08\/federacion-halterofilia1.png\" alt=\"federacion halterofilia1\" \/>\n\t\t\t\t\t\t\t<img itemprop=\"image\" class=\"edgtf-cc-hover-image\" src=\"https:\/\/boxolimpo.com\/wp-content\/uploads\/2018\/08\/federacion-halterofilia.png\" alt=\"federacion halterofilia crossfit malaga\" \/>\n\t\t\t\t\t<\/a>\n\t<\/div><\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"LUNES a) Calentamiento b) Fuerza Back Squat + Lunges + A-Jumps c) Wod Thruster \/ V-ups \/ Pull ups MARTES a) Calentamiento b) Fuerza KB Swing + Run\/Machine + T2B c) Wod Amrap 20' - Parejas MI\u00c9RCOLES a) Calentamiento b) [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7\u25b7 Box Olimpo M\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\u00e1laga. Hyrox M\u00e1laga<\/title>\n<meta name=\"description\" content=\"Centro de Crosstraining en M\u00e1laga. Halterofilia, gimn\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\u00e1laga. Hyrox M\u00e1laga\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boxolimpo.com\/en_us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7\u25b7 Box Olimpo M\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\u00e1laga. Hyrox M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Centro de Crosstraining en M\u00e1laga. Halterofilia, gimn\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\u00e1laga. Hyrox M\u00e1laga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boxolimpo.com\/en_us\/\" \/>\n<meta property=\"og:site_name\" content=\"Box Olimpo M\u00e1laga\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:19:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boxolimpo.com\/#website\",\"url\":\"https:\/\/boxolimpo.com\/\",\"name\":\"Box Olimpo M\\u00e1laga\",\"description\":\"CrossFit M\\u00e1laga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boxolimpo.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boxolimpo.com\/#webpage\",\"url\":\"https:\/\/boxolimpo.com\/\",\"name\":\"\\u25b7\\u25b7 Box Olimpo M\\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\\u00e1laga. Hyrox M\\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\/\/boxolimpo.com\/#website\"},\"datePublished\":\"2017-03-31T09:39:46+00:00\",\"dateModified\":\"2026-05-11T15:19:11+00:00\",\"description\":\"Centro de Crosstraining en M\\u00e1laga. Halterofilia, gimn\\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\\u00e1laga. Hyrox M\\u00e1laga\",\"breadcrumb\":{\"@id\":\"https:\/\/boxolimpo.com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boxolimpo.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boxolimpo.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/boxolimpo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Box Olimpo M\\u00e1laga &#8211; CrossFit M\\u00e1laga &#8211; Hyrox M\\u00e1laga\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7\u25b7 Box Olimpo M\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\u00e1laga. Hyrox M\u00e1laga","description":"Centro de Crosstraining en M\u00e1laga. Halterofilia, gimn\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\u00e1laga. Hyrox M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boxolimpo.com\/en_us\/","og_locale":"en_US","og_type":"article","og_title":"\u25b7\u25b7 Box Olimpo M\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\u00e1laga. Hyrox M\u00e1laga","og_description":"Centro de Crosstraining en M\u00e1laga. Halterofilia, gimn\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\u00e1laga. Hyrox M\u00e1laga","og_url":"https:\/\/boxolimpo.com\/en_us\/","og_site_name":"Box Olimpo M\u00e1laga","article_modified_time":"2026-05-11T15:19:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/boxolimpo.com\/#website","url":"https:\/\/boxolimpo.com\/","name":"Box Olimpo M\u00e1laga","description":"CrossFit M\u00e1laga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boxolimpo.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/boxolimpo.com\/#webpage","url":"https:\/\/boxolimpo.com\/","name":"\u25b7\u25b7 Box Olimpo M\u00e1laga - Centro de Crosstraining. Fuerza y Acondicionamiento. Crossfit M\u00e1laga. Hyrox M\u00e1laga","isPartOf":{"@id":"https:\/\/boxolimpo.com\/#website"},"datePublished":"2017-03-31T09:39:46+00:00","dateModified":"2026-05-11T15:19:11+00:00","description":"Centro de Crosstraining en M\u00e1laga. Halterofilia, gimn\u00e1sticos y DEKA fit - Endurance. Hybrid Training. Musculaci\u00f3n. Abierto de Lunes a Viernes de 7.00-22h, S\u00e1bados de 9.00 -12.00h y Domingos de 9.00-12.00h. Todos los niveles. Crossfit M\u00e1laga. Hyrox M\u00e1laga","breadcrumb":{"@id":"https:\/\/boxolimpo.com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boxolimpo.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/boxolimpo.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/boxolimpo.com\/"},{"@type":"ListItem","position":2,"name":"Box Olimpo M\u00e1laga &#8211; CrossFit M\u00e1laga &#8211; Hyrox M\u00e1laga"}]}]}},"_links":{"self":[{"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/pages\/7000"}],"collection":[{"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/comments?post=7000"}],"version-history":[{"count":55,"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/pages\/7000\/revisions"}],"predecessor-version":[{"id":11497,"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/pages\/7000\/revisions\/11497"}],"wp:attachment":[{"href":"https:\/\/boxolimpo.com\/en_us\/wp-json\/wp\/v2\/media?parent=7000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}